{"id":4081,"date":"2022-04-22T10:05:18","date_gmt":"2022-04-22T08:05:18","guid":{"rendered":"https:\/\/www.hipac.com\/?post_type=usage&#038;p=4081"},"modified":"2022-04-30T16:46:00","modified_gmt":"2022-04-30T14:46:00","slug":"profilati-alluminio","status":"publish","type":"usage","link":"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/","title":{"rendered":"Profilati alluminio"},"content":{"rendered":"\n  <div class=\"section section-title-area \" style=\"\">\n    <div class=\"block-image image--left image--cover image--center-center\" style=\"background-image: url(https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/bg-green-logo.jpg)\"><\/div>\n    <div class=\"container\">\n      <div class=\"row\">\n        <div class=\"col-xs-12 col-md-4\">\n          <div class=\"section-title block-title\">\n                              <div class=\"title-over text-white\">\n                  <div class=\"circle circle-red circle--inline\"><\/div>\n                  PROFILATI ALLUMINIO                <\/div>\n                          \n                              <div class=\"section-title text-white\">\n                  <h3>Rientrano in questo settore tutte le tipologie di profilati in allumino ed altri metalli dalle forme pi\u00f9 differenti.<\/h3>\n                <\/div>\n                        <\/div>\n        <\/div>\n        <div class=\"col-xs-12 col-md-8\">\n          <div class=\"block-text\">\n                              <div class=\"section-title\">\n                  <h3>Criticit\u00e0<\/h3>\n                <\/div>\n                                            <div class=\"list-icon\">\n<ul class=\"list-unstyled\">\n<li>Il film deve resistere alle elevatissime velocita\u2019 di avvolgimento che caratterizzano questo settore<\/li>\n<li>Il film non deve rovinare in alcun modo il prodotto in avvolgimento, che in alcuni casi potrebbe essere ancora caldo<\/li>\n<li>I profilati vengono solitamente impilati su pallet e successivamente sfilati uno ad uno: il film non deve rompersi durante quest\u2019ultima operazione<\/li>\n<\/ul>\n<\/div>\n                 \n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n\n\n\n<div class=\"section section-half  half-right bg-grey\" style=\"\">\n  <div class=\"block-image image--right image--cover\" style=\"background-image: url(https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/img-pannellieprofilatialluminio.jpg);\"><\/div>\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-xs-12 col-md-7 \">\n        <div class=\"block-text\">\n                          <div class=\"section-title\">\n                <h3>Soluzioni HIPAC<\/h3>\n              <\/div>\n                        <div class=\"content-margin-left\">\n                                  <p>Il film premium consigliato per questo tipo di applicazione \u00e8 il 333 rigid power, in spessore da 9 a 17 \u00b5m.<br \/>\nIl film \u00e8 disponibile in versione slippery o extra slippery per evitare che il film si laceri quando I profilati vengono sfilati l\u2019uno dall\u2019altro.<\/p>\n                   \n                               \n            <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<div class=\"section section-sectors \" style=\"\">\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-xs-12\">\n        <div class=\"section-title\">\n                         \n                          <h3>PRODOTTI HIPAC<\/h3>\n                    <\/div>\n      <\/div>\n    <\/div>\n        \n    <div class=\"scrolling-container\">\n      <div class=\"row\">\n                  <div class=\"col-xs-12 col-md-4\">\n            <a href=\"https:\/\/www.hipac.com\/it\/prodotto\/333-rigid-power\/\">\n              <div class=\"card card-content-overlay\">\n                  <div class=\"card-body\">\n                                                              <div class=\"card-bg\" style=\"background-image: url(https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/produzione-rotoli-film-estensibile.jpg);\"><\/div>\n                                    \n                  <div class=\"card-content\">\n                      <div class=\"card-img\" style=\"background-image: url(https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/img-333.svg);\"><\/div>\n                      <h4 class=\"card-title\">\n                      <div class=\"circle circle-red circle--inline\"><\/div>\n                      333 Rigid Power                      <\/h4>\n                      <p>Film rigido per avvolgitrici \u201centry-level\u201d a prestiro medio.<\/p>\n                  <\/div>\n                  <\/div>\n              <\/div>\n            <\/a>\n          <\/div>\n              <\/div>\n    <\/div>\n      <\/div>\n<\/div>\n\n\n\n\n<div class=\"section bg-grey\" style=\"\">\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-xs-12\">\n        <div class=\"section-title title-center\">\n           \n                    <div class=\"section-title\">\n            <h3>I vantaggi dei film HIPAC<\/h3>\n          <\/div>\n                      \n        <\/div>\n      <\/div>\n    <\/div>  \n          \n      <div class=\"scrolling-container\">\n        <div class=\"row\">\n           \n\n            <div class=\"col-xs-12 col-md-3\">\n              <div class=\"block-icon\">\n                <img decoding=\"async\" class=\"mb-1\" src=\"https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/icon-slippery.svg\" style=\"max-widht:100%;width:auto;height:64px;\" \/>\n                <p>Disponibili in versione slippery o extra slippery<\/p>\n              <\/div>\n            <\/div>\n\n           \n\n            <div class=\"col-xs-12 col-md-3\">\n              <div class=\"block-icon\">\n                <img decoding=\"async\" class=\"mb-1\" src=\"https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/icon-resistenza.svg\" style=\"max-widht:100%;width:auto;height:64px;\" \/>\n                <p>Elevata resistenza alla puntura<\/p>\n              <\/div>\n            <\/div>\n\n           \n\n            <div class=\"col-xs-12 col-md-3\">\n              <div class=\"block-icon\">\n                <img decoding=\"async\" class=\"mb-1\" src=\"https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/logo-netroll@2x.svg\" style=\"max-widht:100%;width:auto;height:64px;\" \/>\n                <p>Disponibili in versione NetRoll<\/p>\n              <\/div>\n            <\/div>\n\n                  <\/div>\n      <\/div>  \n      <\/div>\n<\/div>\n\n\n\n\n<div class=\"section \" style=\"background-image: url(https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/bg-pannellieprofilatialluminio-ch.jpg);\">\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-xs-12\">\n        <div class=\"card card-case-study\">\n          <div class=\"card-body\">\n            <div class=\"section-title\">\n                        \n                <div class=\"title-over\">\n                  <div class=\"circle circle-red circle--inline\"><\/div>\n                   CASE STUDY: PROFILATI ALLUMINIO                <\/div>\n                        \n                              <h3>UN ESEMPIO DEL RISPARMIO CHE SI PUO&#8217; OTTENERE CON I FILM PREMIUM HIPAC<\/h3>\n                  \n            <\/div>\n            <div class=\"row\">\n              <div class=\"col-xs-12 col-sm-6\">\n                <div class=\"section-title\">\n                  <h4>UNIT\u00c0 DI CARICO<\/h4>\n                <\/div>\n                <table class=\"table table-half\">\n                <tbody><tr><td>Merce<\/td><td>Profilati in alluminio<\/td><tr><td>Dimensioni<\/td><td>650 x 7 x 7 (H) cm<\/td><tr><td>Peso<\/td><td>85 kg<\/td><tr><td>Profilo<\/td><td>Regolare (A)<\/td><\/tbody>                <\/table>\n              <\/div>\n              <div class=\"col-xs-12 col-sm-6\">\n                <div class=\"section-title\">\n                  <h4>MACCHINA AVVOLGITRICE<\/h4>\n                <\/div>\n                <table class=\"table table-half\">\n                <tbody><tr><td>Modello<\/td><td>Messers\u00ec AGV 470 BI<\/td><tr><td>Tipo<\/td><td>Anello orizzontale<\/td><tr><td>Velocit\u00e0<\/td><td>180 rpm<\/td><tr><td>Carrello portabobina\n<\/td><td>stiro meccanico<\/td><\/tbody>                <\/table>\n              <\/div>\n            <\/div>\n            <div class=\"row\">\n              <div class=\"col-xs-12\">\n                <div class=\"table-first-column-fixed\">\n                  <div class=\"outer\">\n                    <div class=\"inner\">\n                        \n                                              <table class=\"first-column-fixed\">\n                        <tr><th class=\"fix\"><div data-mh=\"columnsRowSameHeight\">Film<\/div><\/th><td class=\"\" data-title=\"Film\"><div data-mh=\"columnsRowSameHeight\">Power Competitor\t<\/div><\/td><td class=\"highlight\" data-title=\"Film\"><div data-mh=\"columnsRowSameHeight\">Hipac 333 Rigid Power\t<\/div><\/td><\/tr><tr><th class=\"fix\"><div data-mh=\"columnsRowSameHeight\">Spessore<\/div><\/th><td class=\"\" data-title=\"Spessore\"><div data-mh=\"columnsRowSameHeight\"><div class=\"text-nowrap\">15 \u00b5m\t<\/div><\/div><\/td><td class=\"highlight\" data-title=\"Spessore\"><div data-mh=\"columnsRowSameHeight\"><div class=\"text-nowrap\">9 \u00b5m\t<\/div><\/div><\/td><\/tr><tr><th class=\"fix\"><div data-mh=\"columnsRowSameHeight\">Stiro\t<\/div><\/th><td class=\"\" data-title=\"Stiro\t\"><div data-mh=\"columnsRowSameHeight\"><div class=\"text-nowrap\">30%<\/div><\/div><\/td><td class=\"highlight\" data-title=\"Stiro\t\"><div data-mh=\"columnsRowSameHeight\"><div class=\"text-nowrap\">30%\t<\/div><\/div><\/td><\/tr><tr><th class=\"fix\"><div data-mh=\"columnsRowSameHeight\">N\u00b0 giri\t<\/div><\/th><td class=\"\" data-title=\"N\u00b0 giri\t\"><div data-mh=\"columnsRowSameHeight\"><div class=\"text-nowrap\">59<\/div><\/div><\/td><td class=\"highlight\" data-title=\"N\u00b0 giri\t\"><div data-mh=\"columnsRowSameHeight\"><div class=\"text-nowrap\">59\t<\/div><\/div><\/td><\/tr><tr><th class=\"fix\"><div data-mh=\"columnsRowSameHeight\">Peso imballo<\/div><\/th><td class=\"\" data-title=\"Peso imballo\"><div data-mh=\"columnsRowSameHeight\">46 g\/pallet<\/div><\/td><td class=\"highlight\" data-title=\"Peso imballo\"><div data-mh=\"columnsRowSameHeight\">25 g\/pallet<\/div><\/td><\/tr><tr><th class=\"fix\"><div data-mh=\"columnsRowSameHeight\">Risparmio\nimballo<\/div><\/th><td class=\"\" data-title=\"Risparmio\nimballo\"><div data-mh=\"columnsRowSameHeight\"><div class=\"text-nowrap\"><\/div><\/div><\/td><td class=\"highlight\" data-title=\"Risparmio\nimballo\"><div data-mh=\"columnsRowSameHeight\"><div class=\"text-success\"><strong>46%<\/strong><\/div>\n<\/div><\/td><\/tr>                      <\/table>\n                    <\/div>\n                  <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n\n<div class=\"section text-white\" style=\"background-image: url(https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/bg-green.jpg);\">\n  <div class=\"container\">\n    <div class=\"row\">\n      <div class=\"col-xs-12\">\n        <div class=\"section-title title-center\">\n                      <div class=\"title-over\">\n              <div class=\"circle circle-red circle--inline\"><\/div>\n              CONTATTACI            <\/div>            \n            \n                      <h3>PROGETTIAMO FILM ESTENSIBILI SPECIALI IN QUALSIASI SETTORE APPLICATIVO<\/h3>\n              \n                \n\n                        <a href=\"#\" data-toggle=\"modal\" data-target=\"#modalRequestInfo\" class=\"btn btn-white\">Contattaci ora<\/a>\n                      \n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n  <div class=\"modal modal-request fade\" id=\"modalRequestInfo\" tabindex=\"-1\" role=\"dialog\"\n    aria-labelledby=\"modalRequestInfoLabel\">\n    <div class=\"modal-dialog modal-lg\" role=\"document\">\n      <div class=\"modal-content\">\n        <div class=\"modal-header\">\n          <button type=\"button\" class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n            <div class=\"icon icon-close\"><\/div>\n          <\/button>\n          <h4 class=\"modal-title\" id=\"modalRequestInfoLabel\">\n            <div class=\"circle circle-red circle--inline\"><\/div>\n            Contatti          <\/h4>\n        <\/div>\n        <div class=\"modal-body\">\n          <div class=\"row\">\n            <div class=\"col-xs-12\">\n              <div class=\"section-title\">\n                <h3>Mettiti in contatto con noi per avere supporto o chiedere informazioni<\/h3>\n              <\/div>\n              <p class=\"mb-2\">Compila il modulo con i tuoi dati per essere ricontattato il prima possibile da un nostro referente<\/p>\n            <\/div>\n          <\/div>\n          <div class=\"row\">\n            <div class=\"col-xs-12\">\n              \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4565-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"4565\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/usage\/4081#wpcf7-f4565-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4565\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4565-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><input type=\"hidden\" name=\"formPageUrl\" value=\"https:\/\/www.hipac.com\/it\/wp-json\/wp\/v2\/usage\/4081\" \/>\n<\/p>\n<div class=\"form-contact\">\n\t<div class=\"row\">\n\t\t<div class=\"col-xs-12 col-sm-6\">\n\t\t\t<p><label>Nome*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"formName\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"formName\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-xs-12 col-sm-6\">\n\t\t\t<p><label>Cognome*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"formSurname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"formSurname\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row\">\n\t\t<div class=\"col-xs-12 col-sm-6\">\n\t\t\t<p><label>Qualifica<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"formQualification\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text form-control\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"formQualification\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-xs-12 col-sm-6\">\n\t\t\t<p><label>Azienda*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"formCompany\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"formCompany\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row\">\n\t\t<div class=\"col-xs-12 col-sm-6\">\n\t\t\t<p><label>Nazione*<\/label><br \/>\n<div class=\"select\"><span class=\"wpcf7-form-control-wrap formCountry\"><select class=\"wpcf7-form-control wpcf7-select_country_list wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" name=\"formCountry\"><option value=\"\">Seleziona&#8230;<\/option><option value=\"1 | Usa\">Usa<\/option><option value=\"2 | Regno unito\">Regno unito<\/option><option value=\"3 | Germania\">Germania<\/option><option value=\"4 | Francia\">Francia<\/option><option value=\"5 | Giappone\">Giappone<\/option><option value=\"6 | Afghanistan\">Afghanistan<\/option><option value=\"7 | Albania\">Albania<\/option><option value=\"8 | Algeria\">Algeria<\/option><option value=\"9 | Andorra\">Andorra<\/option><option value=\"10 | Angola\">Angola<\/option><option value=\"11 | Anguilla\">Anguilla<\/option><option value=\"12 | Antigua &#038; barbuda\">Antigua &#038; barbuda<\/option><option value=\"13 | Argentina\">Argentina<\/option><option value=\"14 | Armenia\">Armenia<\/option><option value=\"15 | Aruba\">Aruba<\/option><option value=\"16 | Australia\">Australia<\/option><option value=\"17 | Austria\">Austria<\/option><option value=\"18 | Azerbaijan\">Azerbaijan<\/option><option value=\"19 | Bahamas\">Bahamas<\/option><option value=\"20 | Baherain\">Baherain<\/option><option value=\"21 | Bangladesh\">Bangladesh<\/option><option value=\"22 | Barbados\">Barbados<\/option><option value=\"23 | Bielorussia\">Bielorussia<\/option><option value=\"24 | Belgio\">Belgio<\/option><option value=\"25 | Belize\">Belize<\/option><option value=\"26 | Benin\">Benin<\/option><option value=\"27 | Bermuda\">Bermuda<\/option><option value=\"28 | Bhutan\">Bhutan<\/option><option value=\"29 | Bolivia\">Bolivia<\/option><option value=\"30 | Bosnia-herzegovina\">Bosnia-herzegovina<\/option><option value=\"31 | Botswana\">Botswana<\/option><option value=\"32 | Brasile\">Brasile<\/option><option value=\"33 | British indian ocean territory\">British indian ocean territory<\/option><option value=\"34 | British virgin islands\">British virgin islands<\/option><option value=\"35 | Brunei\">Brunei<\/option><option value=\"36 | Bulgaria\">Bulgaria<\/option><option value=\"37 | Burkina faso\">Burkina faso<\/option><option value=\"38 | Burundi\">Burundi<\/option><option value=\"39 | Cambodia\">Cambodia<\/option><option value=\"40 | Cameroon\">Cameroon<\/option><option value=\"41 | Canada\">Canada<\/option><option value=\"42 | Cape verde\">Cape verde<\/option><option value=\"43 | Cayman islands\">Cayman islands<\/option><option value=\"44 | Central african republic\">Central african republic<\/option><option value=\"45 | Chad\">Chad<\/option><option value=\"46 | Chile\">Chile<\/option><option value=\"47 | China (mainland)\">China (mainland)<\/option><option value=\"48 | Christmas island (indian ocean)\">Christmas island (indian ocean)<\/option><option value=\"49 | Cocos (keeling) islands\">Cocos (keeling) islands<\/option><option value=\"50 | Colombia\">Colombia<\/option><option value=\"51 | Comoros\">Comoros<\/option><option value=\"52 | Congo\">Congo<\/option><option value=\"53 | Cook islands\">Cook islands<\/option><option value=\"54 | Costa rica\">Costa rica<\/option><option value=\"55 | Croatia\">Croatia<\/option><option value=\"56 | Cipro\">Cipro<\/option><option value=\"57 | Repubblica ceca\">Repubblica ceca<\/option><option value=\"58 | Danimarca\">Danimarca<\/option><option value=\"59 | Djibouti\">Djibouti<\/option><option value=\"60 | Dominica\">Dominica<\/option><option value=\"61 | Repubblica dominicana\">Repubblica dominicana<\/option><option value=\"62 | Ecuador\">Ecuador<\/option><option value=\"63 | Egitto\">Egitto<\/option><option value=\"64 | El salvador\">El salvador<\/option><option value=\"65 | Guinea Equatoriale\">Guinea equatoriale<\/option><option value=\"66 | Eritrea\">Eritrea<\/option><option value=\"67 | Estonia\">Estonia<\/option><option value=\"68 | Ethiopia\">Ethiopia<\/option><option value=\"69 | Isole falkland\">Isole falkland<\/option><option value=\"70 | Isole faroe\">Isole faroe<\/option><option value=\"71 | Fiji\">Fiji<\/option><option value=\"72 | Finlandia\">Finlandia<\/option><option value=\"73 | Fr southern &#038; antartic lands\">Fr southern &#038; antartic lands<\/option><option value=\"74 | French guiana\">French guiana<\/option><option value=\"75 | French polynesia\">French polynesia<\/option><option value=\"76 | Gabon\">Gabon<\/option><option value=\"78 | Georgia\">Georgia<\/option><option value=\"79 | Ghana\">Ghana<\/option><option value=\"80 | Gibraltar\">Gibraltar<\/option><option value=\"81 | Grecia\">Grecia<\/option><option value=\"82 | Groenlandia\">Groenlandia<\/option><option value=\"83 | Grenada\">Grenada<\/option><option value=\"84 | Guadeloupe\">Guadeloupe<\/option><option value=\"85 | Guatemala\">Guatemala<\/option><option value=\"86 | Guinea\">Guinea<\/option><option value=\"87 | Guinea-bissau\">Guinea-bissau<\/option><option value=\"88 | Guyana\">Guyana<\/option><option value=\"89 | Haiti\">Haiti<\/option><option value=\"90 | Heard and mcdonald islands\">Heard and mcdonald islands<\/option><option value=\"91 | Honduras\">Honduras<\/option><option value=\"92 | Hong kong\">Hong kong<\/option><option value=\"93 | Ungheria\">Ungheria<\/option><option value=\"94 | Islanda\">Islanda<\/option><option value=\"95 | India\">India<\/option><option value=\"96 | Indonesia\">Indonesia<\/option><option value=\"97 | Israele\">Israele<\/option><option value=\"98 | Italia\">Italia<\/option><option value=\"99 | Costa d'avorio\">Costa d&#8217;avorio<\/option><option value=\"100 | Jamaica\">Jamaica<\/option><option value=\"101 | Giordania\">Giordania<\/option><option value=\"102 | Kazakhstan\">Kazakhstan<\/option><option value=\"103 | Kenya\">Kenya<\/option><option value=\"104 | Kiribati\">Kiribati<\/option><option value=\"105 | Kuwait\">Kuwait<\/option><option value=\"106 | Kyrgyzstan\">Kyrgyzstan<\/option><option value=\"107 | Laos\">Laos<\/option><option value=\"108 | Lettonia\">Lettonia<\/option><option value=\"109 | Lebanon\">Lebanon<\/option><option value=\"110 | Lesotho\">Lesotho<\/option><option value=\"111 | Liberia\">Liberia<\/option><option value=\"112 | Liechtenstein\">Liechtenstein<\/option><option value=\"113 | Lithuania\">Lithuania<\/option><option value=\"114 | Lussemburgo\">Lussemburgo<\/option><option value=\"115 | Macao (macau)\">Macao (macau)<\/option><option value=\"117 | Madagascar\">Madagascar<\/option><option value=\"118 | Malawi\">Malawi<\/option><option value=\"119 | Malaysia\">Malaysia<\/option><option value=\"120 | Maldive\">Maldive<\/option><option value=\"121 | Mali\">Mali<\/option><option value=\"122 | Malta e gozo\">Malta e gozo<\/option><option value=\"123 | Isole Marshall\">Isole marshall<\/option><option value=\"124 | Martinique\">Martinique<\/option><option value=\"125 | Mauritania\">Mauritania<\/option><option value=\"126 | Mauritius\">Mauritius<\/option><option value=\"127 | Messico\">Messico<\/option><option value=\"128 | Micronesia, federated states\">Micronesia, federated states<\/option><option value=\"129 | Moldavia\">Moldavia<\/option><option value=\"130 | Monaco\">Monaco<\/option><option value=\"131 | Mongolia\">Mongolia<\/option><option value=\"132 | Montenegro\">Montenegro<\/option><option value=\"133 | Montserrat\">Montserrat<\/option><option value=\"134 | Marocco\">Marocco<\/option><option value=\"135 | Mozambique\">Mozambique<\/option><option value=\"136 | Myanmar (burma)\">Myanmar (burma)<\/option><option value=\"137 | Namibia\">Namibia<\/option><option value=\"138 | Nauru\">Nauru<\/option><option value=\"139 | Nepal\">Nepal<\/option><option value=\"140 | Olanda\">Olanda<\/option><option value=\"142 | Nuova caledonia\">Nuova caledonia<\/option><option value=\"143 | Nuova zelanda\">Nuova zelanda<\/option><option value=\"144 | Nicaragua\">Nicaragua<\/option><option value=\"145 | Niger\">Niger<\/option><option value=\"146 | Nigeria\">Nigeria<\/option><option value=\"147 | Niue\">Niue<\/option><option value=\"148 | Isola di Norfolk\">Isola di norfolk<\/option><option value=\"150 | Norvegia\">Norvegia<\/option><option value=\"151 | Oman\">Oman<\/option><option value=\"152 | Pakistan\">Pakistan<\/option><option value=\"153 | Palau\">Palau<\/option><option value=\"154 | Panama\">Panama<\/option><option value=\"155 | Papua new guinea\">Papua new guinea<\/option><option value=\"156 | Paraguay\">Paraguay<\/option><option value=\"157 | Peru\">Peru<\/option><option value=\"158 | Filippine\">Filippine<\/option><option value=\"159 | Pitcairn\">Pitcairn<\/option><option value=\"160 | Polonia\">Polonia<\/option><option value=\"161 | Portogallo\">Portogallo<\/option><option value=\"162 | Puerto rico\">Puerto rico<\/option><option value=\"163 | Qatar\">Qatar<\/option><option value=\"164 | Irlanda\">Irlanda<\/option><option value=\"165 | Reunion (island, french)\">Reunion (island, french)<\/option><option value=\"166 | Romania\">Romania<\/option><option value=\"167 | Russia\">Russia<\/option><option value=\"168 | Rwanda\">Rwanda<\/option><option value=\"169 | San marino\">San marino<\/option><option value=\"170 | Sao Tome e Principe\">Sao tome e principe<\/option><option value=\"171 | Saudi arabia\">Saudi arabia<\/option><option value=\"172 | Senegal\">Senegal<\/option><option value=\"173 | Serbia\">Serbia<\/option><option value=\"174 | Seychelles\">Seychelles<\/option><option value=\"175 | Sierra leone\">Sierra leone<\/option><option value=\"176 | Singapore\">Singapore<\/option><option value=\"177 | Slovakia\">Slovakia<\/option><option value=\"178 | Slovenia\">Slovenia<\/option><option value=\"179 | Isole Salomone\">Isole salomone<\/option><option value=\"180 | Somalia\">Somalia<\/option><option value=\"181 | Sud Africa\">Sud africa<\/option><option value=\"182 | Corea del Sud\">Corea del sud<\/option><option value=\"183 | Spagna\">Spagna<\/option><option value=\"184 | Sri lanka\">Sri lanka<\/option><option value=\"185 | St christopher-nevis\">St christopher-nevis<\/option><option value=\"186 | St helena\">St helena<\/option><option value=\"187 | Santa Lucia\">Santa lucia<\/option><option value=\"188 | St pierre and miquelon\">St pierre and miquelon<\/option><option value=\"189 | Saint Vincent e Grenadine\">Saint vincent e grenadine<\/option><option value=\"190 | Suriname\">Suriname<\/option><option value=\"191 | Svalbard e Jan Mayen\">Svalbard e jan mayen<\/option><option value=\"192 | Swaziland\">Swaziland<\/option><option value=\"193 | Svezia\">Svezia<\/option><option value=\"194 | Svizzera\">Svizzera<\/option><option value=\"195 | Taiwan\">Taiwan<\/option><option value=\"196 | Tagikistan\">Tagikistan<\/option><option value=\"197 | Tanzania\">Tanzania<\/option><option value=\"198 | Tailandia\">Tailandia<\/option><option value=\"199 | Gambia\">Gambia<\/option><option value=\"200 | Togo\">Togo<\/option><option value=\"202 | Tonga\">Tonga<\/option><option value=\"203 | Trinidad e Tobago\">Trinidad e tobago<\/option><option value=\"204 | Tunisia\">Tunisia<\/option><option value=\"205 | Turchia\">Turchia<\/option><option value=\"206 | Turkmenistan\">Turkmenistan<\/option><option value=\"207 | Turchi e Isole Caicos\">Turchi e isole caicos<\/option><option value=\"208 | Tuvalu\">Tuvalu<\/option><option value=\"209 | Uganda\">Uganda<\/option><option value=\"210 | Ucraina\">Ucraina<\/option><option value=\"211 | Emirati Arabi Uniti\">Emirati arabi uniti<\/option><option value=\"212 | Uruguay\">Uruguay<\/option><option value=\"213 | Uzbekistan\">Uzbekistan<\/option><option value=\"214 | Vanuatu\">Vanuatu<\/option><option value=\"215 | Stato della Citt\u00e0 del Vaticano\">Stato della citt\u00e0 del vaticano<\/option><option value=\"216 | Venezuela\">Venezuela<\/option><option value=\"217 | Vietnam\">Vietnam<\/option><option value=\"218 | Isole Vergini (USA)\">Isole vergini (usa)<\/option><option value=\"219 | Wallis and futuna\">Wallis and futuna<\/option><option value=\"221 | Sahara occidentale\">Sahara occidentale<\/option><option value=\"222 | Western samoa\">Western samoa<\/option><option value=\"223 | Yemen (sana)\">Yemen (sana)<\/option><option value=\"226 | Zambia\">Zambia<\/option><option value=\"227 | Zimbabwe\">Zimbabwe<\/option><\/select><div class=\"select__arrow\"><\/div><\/span><\/div>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-xs-12 col-sm-6\">\n\t\t\t<div class=\"form-group\">\n\t\t\t\t<p><label>Citt\u00e0*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"formCity\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"formCity\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row\">\n\t\t<div class=\"col-xs-12 col-sm-6\">\n\t\t\t<div class=\"form-group\">\n\t\t\t\t<p><label>Telefono<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"formPhone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text form-control\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"formPhone\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-xs-12 col-sm-6\">\n\t\t\t<div class=\"form-group\">\n\t\t\t\t<p><label>Email*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"formEmail\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"formEmail\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-xs-12\">\n\t\t\t<p><label>Messaggio*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"formDescription\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" name=\"formDescription\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-xs-12 col-sm-8 mt-2\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"formPrivacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"formPrivacy\" value=\"1\" class=\"form-check-input\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">* Acconsento a che i miei dati personali vengano utilizzati in accordo con la <a href=\"https:\/\/www.iubenda.com\/privacy-policy\/13910715\" target=\"_blank\">Privacy Policy<\/a><\/span><\/label><\/span><\/span><\/span><span class=\"wpcf7-form-control-wrap\" data-name=\"formMarketing\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"formMarketing\" value=\"1\" class=\"form-check-input\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Autorizzo il trattamento dei miei dati personali per essere aggiornato sui nuovi arrivi e per le finalit\u00e0 di marketing diretto correlate ai servizi offerti.<\/span><\/label><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-sm-4 mt-2 hidden-xs text-right\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-secondary\" type=\"submit\" value=\"Invia richiesta\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-xs-12 mt-2 visible-xs\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-secondary\" type=\"submit\" value=\"Invia richiesta\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":4088,"template":"","usage_category":[94],"product_benefit":[130,80,83],"class_list":["post-4081","usage","type-usage","status-publish","has-post-thumbnail","hentry","usage_category-pannelli-e-profilati","product_benefit-disponibili-versione-slippery","product_benefit-elevata-resistenza-alla-puntura","product_benefit-disponibili-in-versione-netroll"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Profilati alluminio - Hipac Group<\/title>\n<meta name=\"description\" content=\"Realizziamo film estensibili per prodotti specifici, come profilati alluminio, destinati al settore dei pannelli e profilati. Scopri di pi\u00f9 sul nostro sito!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profilati alluminio - Hipac Group\" \/>\n<meta property=\"og:description\" content=\"Realizziamo film estensibili per prodotti specifici, come profilati alluminio, destinati al settore dei pannelli e profilati. Scopri di pi\u00f9 sul nostro sito!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/\" \/>\n<meta property=\"og:site_name\" content=\"Hipac Group\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-30T14:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/bg-pannellieprofilatialluminio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/applicazione\\\/profilati-alluminio\\\/\",\"url\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/applicazione\\\/profilati-alluminio\\\/\",\"name\":\"Profilati alluminio - Hipac Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/applicazione\\\/profilati-alluminio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/applicazione\\\/profilati-alluminio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hipac.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/bg-pannellieprofilatialluminio.jpg\",\"datePublished\":\"2022-04-22T08:05:18+00:00\",\"dateModified\":\"2022-04-30T14:46:00+00:00\",\"description\":\"Realizziamo film estensibili per prodotti specifici, come profilati alluminio, destinati al settore dei pannelli e profilati. Scopri di pi\u00f9 sul nostro sito!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/applicazione\\\/profilati-alluminio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hipac.com\\\/it\\\/applicazione\\\/profilati-alluminio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/applicazione\\\/profilati-alluminio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hipac.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/bg-pannellieprofilatialluminio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hipac.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/bg-pannellieprofilatialluminio.jpg\",\"width\":1920,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/applicazione\\\/profilati-alluminio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Applicazioni\",\"item\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/applicazione\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profilati alluminio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/\",\"name\":\"Hipac Group\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hipac.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Profilati alluminio - Hipac Group","description":"Realizziamo film estensibili per prodotti specifici, come profilati alluminio, destinati al settore dei pannelli e profilati. Scopri di pi\u00f9 sul nostro sito!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/","og_locale":"it_IT","og_type":"article","og_title":"Profilati alluminio - Hipac Group","og_description":"Realizziamo film estensibili per prodotti specifici, come profilati alluminio, destinati al settore dei pannelli e profilati. Scopri di pi\u00f9 sul nostro sito!","og_url":"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/","og_site_name":"Hipac Group","article_modified_time":"2022-04-30T14:46:00+00:00","og_image":[{"width":1920,"height":400,"url":"https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/bg-pannellieprofilatialluminio.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/","url":"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/","name":"Profilati alluminio - Hipac Group","isPartOf":{"@id":"https:\/\/www.hipac.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/#primaryimage"},"image":{"@id":"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/bg-pannellieprofilatialluminio.jpg","datePublished":"2022-04-22T08:05:18+00:00","dateModified":"2022-04-30T14:46:00+00:00","description":"Realizziamo film estensibili per prodotti specifici, come profilati alluminio, destinati al settore dei pannelli e profilati. Scopri di pi\u00f9 sul nostro sito!","breadcrumb":{"@id":"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/#primaryimage","url":"https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/bg-pannellieprofilatialluminio.jpg","contentUrl":"https:\/\/www.hipac.com\/wp-content\/uploads\/2022\/04\/bg-pannellieprofilatialluminio.jpg","width":1920,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.hipac.com\/it\/applicazione\/profilati-alluminio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Applicazioni","item":"https:\/\/www.hipac.com\/it\/applicazione\/"},{"@type":"ListItem","position":2,"name":"Profilati alluminio"}]},{"@type":"WebSite","@id":"https:\/\/www.hipac.com\/it\/#website","url":"https:\/\/www.hipac.com\/it\/","name":"Hipac Group","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hipac.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.hipac.com\/it\/wp-json\/wp\/v2\/usage\/4081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hipac.com\/it\/wp-json\/wp\/v2\/usage"}],"about":[{"href":"https:\/\/www.hipac.com\/it\/wp-json\/wp\/v2\/types\/usage"}],"version-history":[{"count":0,"href":"https:\/\/www.hipac.com\/it\/wp-json\/wp\/v2\/usage\/4081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hipac.com\/it\/wp-json\/wp\/v2\/media\/4088"}],"wp:attachment":[{"href":"https:\/\/www.hipac.com\/it\/wp-json\/wp\/v2\/media?parent=4081"}],"wp:term":[{"taxonomy":"usage_category","embeddable":true,"href":"https:\/\/www.hipac.com\/it\/wp-json\/wp\/v2\/usage_category?post=4081"},{"taxonomy":"product_benefit","embeddable":true,"href":"https:\/\/www.hipac.com\/it\/wp-json\/wp\/v2\/product_benefit?post=4081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}